{"id":25,"date":"2018-12-05T12:44:22","date_gmt":"2018-12-05T12:44:22","guid":{"rendered":"https:\/\/wilmer.qodeinteractive.com\/elementor\/?page_id=25"},"modified":"2026-03-31T17:27:37","modified_gmt":"2026-03-31T17:27:37","slug":"main-home","status":"publish","type":"page","link":"https:\/\/brentac.com.mx\/","title":{"rendered":"Main Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\">\n\t\t\t\t<div class=\"mkdf-elementor-row\" style=\"\">\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c562b46 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"c562b46\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b15a2ca\" data-id=\"b15a2ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5caeb25 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5caeb25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2>Desarrollo Integral de Proyectos de Obra Civil e Infraestructura Industrial<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c94544 elementor-widget elementor-widget-text-editor\" data-id=\"3c94544\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5>\u00a0<\/h5><h5>Desde la cimentaci\u00f3n hasta la puesta en operaci\u00f3n, ejecutamos proyectos con enfoque en seguridad, trazabilidad, cumplimiento t\u00e9cnico y eficiencia operativa, alineados a est\u00e1ndares internacionales y requerimientos de plantas industriales de alta exigencia.<\/h5>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e796a64 elementor-widget elementor-widget-text-editor\" data-id=\"e796a64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Brentac no solo construye\u2026 garantiza continuidad operativa, seguridad estructural y cumplimiento en proyectos donde el margen de error es cero.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-text-holder mkdf-row-background-text-front\"><div class=\"mkdf-row-background-text-wrapper mkdf-row-background-text-animation mkdf-row-background-text-align-left\"><div class=\"mkdf-row-background-text-wrapper-inner\" style=\"font-size:180px;text-align:left;vertical-align:middle;padding-left:220px\" data-font-size-1440=180px data-font-size-1280=180px data-padding-left-size-1440=4.3% data-padding-left-size-1280=4.3%><div class=\"mkdf-row-background-text-1\">brentac<\/div><\/div><\/div><\/div><\/div>\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-030ddac mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"030ddac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d4b8c00\" data-id=\"d4b8c00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2ac6e0 elementor-widget__width-initial elementor-widget elementor-widget-mkdf_banner\" data-id=\"d2ac6e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-banner-holder  mkdf-hover-background-color mkdf-banner-info-default\">\n    <div class=\"mkdf-banner-image\">\n            <\/div>\n    <div class=\"mkdf-banner-text-holder\" style=\"padding: 35px 22px 31px 0\">\n\t    <div class=\"mkdf-banner-text-outer\">\n\t\t    <div class=\"mkdf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"mkdf-banner-subtitle\" style=\"font-size: 12px\">\n\t\t\t            nuestros servicios \t\t            <\/h5>\n\t\t        \t\t        \t\t            <h4 class=\"mkdf-banner-title\" style=\"margin-top: -3px\">\n\t\t                Estructuras Met\u00e1licas\t                <\/h4>\n\t\t        \t\t\t\t                    <a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\"  class=\"mkdf-btn mkdf-btn-medium mkdf-btn-simple\"  >\n    <span class=\"mkdf-btn-text\"><\/span>\n    <\/a>\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"mkdf-banner-link\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\"><\/a>\n    <div class=\"mkdf-banner-bottom-line\" ><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0edc7a3\" data-id=\"0edc7a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01554ef elementor-widget elementor-widget-mkdf_banner\" data-id=\"01554ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-banner-holder  mkdf-hover-background-color mkdf-banner-info-default\">\n    <div class=\"mkdf-banner-image\">\n            <\/div>\n    <div class=\"mkdf-banner-text-holder\" style=\"padding: 35px 22px 31px 0\">\n\t    <div class=\"mkdf-banner-text-outer\">\n\t\t    <div class=\"mkdf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"mkdf-banner-subtitle\" style=\"font-size: 12px\">\n\t\t\t            nuestros servicios \t\t            <\/h5>\n\t\t        \t\t        \t\t            <h4 class=\"mkdf-banner-title\" style=\"margin-top: -3px\">\n\t\t                Obra civil\t                <\/h4>\n\t\t        \t\t\t\t                    <a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/three-columns\/\" target=\"_self\"  class=\"mkdf-btn mkdf-btn-medium mkdf-btn-simple\"  >\n    <span class=\"mkdf-btn-text\"><\/span>\n    <\/a>\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"mkdf-banner-link\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/three-columns\/\" target=\"_self\"><\/a>\n    <div class=\"mkdf-banner-bottom-line\" ><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-acd3686\" data-id=\"acd3686\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e51017a elementor-widget elementor-widget-mkdf_banner\" data-id=\"e51017a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-banner-holder  mkdf-hover-background-color mkdf-banner-info-default\">\n    <div class=\"mkdf-banner-image\">\n            <\/div>\n    <div class=\"mkdf-banner-text-holder\" style=\"padding: 35px 22px 31px 0\">\n\t    <div class=\"mkdf-banner-text-outer\">\n\t\t    <div class=\"mkdf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"mkdf-banner-subtitle\" style=\"font-size: 12px\">\n\t\t\t            NUESTROS SERVICIOS\t\t            <\/h5>\n\t\t        \t\t        \t\t            <h4 class=\"mkdf-banner-title\" style=\"margin-top: -3px\">\n\t\t                Soldadura Industrial\t                <\/h4>\n\t\t        \t\t\t\t                    <a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\"  class=\"mkdf-btn mkdf-btn-medium mkdf-btn-simple\"  >\n    <span class=\"mkdf-btn-text\"><\/span>\n    <\/a>\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"mkdf-banner-link\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\"><\/a>\n    <div class=\"mkdf-banner-bottom-line\" ><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-554b235\" data-id=\"554b235\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a84b86b elementor-widget elementor-widget-mkdf_banner\" data-id=\"a84b86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-banner-holder  mkdf-hover-background-color mkdf-banner-info-default\">\n    <div class=\"mkdf-banner-image\">\n            <\/div>\n    <div class=\"mkdf-banner-text-holder\" style=\"padding: 35px 22px 31px 0\">\n\t    <div class=\"mkdf-banner-text-outer\">\n\t\t    <div class=\"mkdf-banner-text-inner\">\n\t\t        \t\t            <h5 class=\"mkdf-banner-subtitle\" style=\"font-size: 12px\">\n\t\t\t            nuestros servicios\t\t            <\/h5>\n\t\t        \t\t        \t\t            <h4 class=\"mkdf-banner-title\" style=\"margin-top: -3px\">\n\t\t                 Instalaciones Hidrosanitarias\t                <\/h4>\n\t\t        \t\t\t\t                    <a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/standard-shader\/\" target=\"_self\"  class=\"mkdf-btn mkdf-btn-medium mkdf-btn-simple\"  >\n    <span class=\"mkdf-btn-text\"><\/span>\n    <\/a>\t\t        \t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t        <a itemprop=\"url\" class=\"mkdf-banner-link\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/standard-shader\/\" target=\"_self\"><\/a>\n    <div class=\"mkdf-banner-bottom-line\" ><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-338d00cc mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"338d00cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6cd90b69\" data-id=\"6cd90b69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78dbe8ab mkdf-appearing-section mkdf-eh-item-project elementor-widget elementor-widget-image\" data-id=\"78dbe8ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-768x576.jpg\" class=\"attachment-medium_large size-medium_large wp-image-9700\" alt=\"nave industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-768x576.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-1024x768.jpg 1024w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-150x113.jpg 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-600x450.jpg 600w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d5acc66\" data-id=\"d5acc66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"mkdf-elementor-row mkdf-row-with-bg-pattern\" style=\"\">\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-584e799b elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"584e799b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68cc1502\" data-id=\"68cc1502\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3528709 elementor-widget__width-initial elementor-widget elementor-widget-mkdf_section_title\" data-id=\"3528709\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-standard   \" >\n\t<div class=\"mkdf-st-inner\">\n        \t\t\t\t\t<h2 class=\"mkdf-st-title\" >\n\t\t\t\t\u00bfPor qu\u00e9 elegirnos?\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"mkdf-st-text\" style=\"margin-top: 20px\">\n\t\t\t\tContamos con la experiencia t\u00e9cnica y la capacidad operativa necesarias para ejecutar proyectos en toda la Rep\u00fablica Mexicana. Nuestro equipo se fortalece mediante capacitaci\u00f3n constante, asegurando altos est\u00e1ndares de calidad, seguridad y cumplimiento en cada obra.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f65e35a elementor-widget elementor-widget-mkdf_button\" data-id=\"f65e35a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/about-us\/\" target=\"_self\"  class=\"mkdf-btn mkdf-btn-medium mkdf-btn-solid\"  >\n    <span class=\"mkdf-btn-text\">Conoce M\u00e1s<\/span>\n    <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-pattern-holder\"><div class=\"mkdf-row-background-pattern-left\"><\/div><div class=\"mkdf-row-background-pattern-right\"><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f069698 elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"f069698\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3603d01\" data-id=\"3603d01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"mkdf-elementor-row\" style=\"\">\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0896a5a mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"0896a5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d839f1d\" data-id=\"d839f1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-text-holder mkdf-row-background-text-front\"><div class=\"mkdf-row-background-text-wrapper mkdf-row-background-text-animation mkdf-row-background-text-align-left\"><div class=\"mkdf-row-background-text-wrapper-inner\" style=\"font-size:180px;color:#1E3C6F;-webkit-text-stroke-color:#1E3C6F;text-align:left;vertical-align:middle;padding-left:220px\" data-font-size-1440=180px data-font-size-1280=180px data-padding-left-size-1440=4.3% data-padding-left-size-1280=4.3%><div class=\"mkdf-row-background-text-1\">Capacidad <\/div><\/div><\/div><\/div><\/div>\t\t<div class=\"elementor-element elementor-element-59093ac elementor-widget elementor-widget-text-editor\" data-id=\"59093ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Capacidad t\u00e9cnica<\/span><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d515761 elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"d515761\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f26a0c\" data-id=\"2f26a0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5ff5e5 elementor-widget__width-auto elementor-widget elementor-widget-mkdf_portfolio_slider\" data-id=\"d5ff5e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_portfolio_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-portfolio-slider-holder mkdf-portfolio-slider-navigation-left-from-slider mkdf-ps-light-skin\"><div class=\"mkdf-portfolio-list-holder mkdf-grid-list mkdf-disable-bottom-space mkdf-pl-gallery mkdf-three-columns mkdf-large-space mkdf-pl-standard-shader    mkdf-pl-pag-no-pagination      mkdf-pl-default-skin\"  data-type=gallery data-skin=default-skin data-item-type=gallery data-number-of-columns= data-space-between-items=large data-number-of-items=1 data-image-proportions=square data-enable-fixed-proportions=no data-enable-image-shadow=no data-orderby=date data-order=ASC data-item-style=standard-shader data-enable-title=yes data-title-tag=h4 data-enable-category=no data-enable-count-images=yes data-enable-excerpt=yes data-excerpt-length=500 data-readmore=no data-pagination-type=no-pagination data-filter=no data-filter-order-by=name data-enable-article-animation=no data-portfolio-slider-on=yes data-enable-loop= data-enable-autoplay=yes data-enable-navigation=no data-navigation-skin= data-enable-pagination=no data-pagination-skin= data-pagination-position= data-enable-auto-width=yes data-max-num-pages=44 data-next-page=2>\n\t\t<div class=\"mkdf-pl-inner mkdf-outer-space mkdf-owl-slider mkdf-list-is-slider clearfix\">\n\t\t<article class=\"mkdf-pl-item mkdf-item-space  post-265 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-skills portfolio-tag-colours portfolio-tag-materials\">\n\t<div class=\"mkdf-pl-item-inner\">\n\t\t<a href=\"https:\/\/brentac.com.mx\/index.php\/portfolio-item\/capacidad-tecnica\/\">\n<div class=\"mkdf-pli-image\">\n\t<img decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-650x650.jpg\" class=\"attachment-wilmer_mikado_image_square size-wilmer_mikado_image_square wp-post-image\" alt=\"constructora industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-650x650.jpg 650w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-1300x1300.jpg 1300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-300x300.jpg 300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div>\n<\/a>\n<div class=\"mkdf-pli-text-holder\" >\n\t<div class=\"mkdf-pli-text-wrapper\">\n\t\t<div class=\"mkdf-pli-text\">\n\n            \n\t\t\t    <a href=\"https:\/\/brentac.com.mx\/index.php\/portfolio-item\/capacidad-tecnica\/\">\n\t<h4 itemprop=\"name\" class=\"mkdf-pli-title entry-title\" >\n\t\tCapacidad t\u00e9cnica\t<\/h4>\n    <\/a>\n\n\t\t\t\t\t<div class=\"mkdf-gli-number-of-images-holder\">\n\t\t\t<span>6 pics<\/span>\n\t\t<\/div>\n\t\n\t\t\t\t<p itemprop=\"description\" class=\"mkdf-pli-excerpt\">En Brentac contamos con la experiencia operativa, el conocimiento t\u00e9cnico y el equipo humano necesario para participar en proyectos de construcci\u00f3n industrial que requieren precisi\u00f3n, disciplina operativa y cumplimiento de altos est\u00e1ndares de calidad.<\/p>\n\n            \n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\n\t\t\t\t\t            <a itemprop=\"url\" class=\"mkdf-pli-link\" data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/construtora-industrial-scaled.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t    \n   \n\t\t<a itemprop=\"url\"  data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/port-gallery-01.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t\t\n\t\t<a itemprop=\"url\"  data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/port-gallery-02.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t\t\n\t\t<a itemprop=\"url\"  data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/port-gallery-03.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t\t\n\t\t<a itemprop=\"url\"  data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/port-gallery-04.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t\t\n\t\t<a itemprop=\"url\"  data-rel=\"prettyPhoto[rel-gallery-item-265-1854976629]\" href=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/port-gallery-05.jpg\" title=\"Capacidad t\u00e9cnica\"><\/a>\n\t\t\t\t\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1da3b87 elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"1da3b87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f3f3001\" data-id=\"f3f3001\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf83476 elementor-widget__width-initial elementor-widget elementor-widget-mkdf_clients_grid\" data-id=\"cf83476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_clients_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"mkdf-clients-grid-holder mkdf-grid-list mkdf-disable-bottom-space mkdf-four-columns mkdf-normal-space  mkdf-cc-hover-roll-over\">\n            <div class=\"mkdf-cg-inner mkdf-outer-space\">\n                <div class=\"mkdf-cc-item mkdf-item-space mkdf-cci-has-link\">\n\t\t\t<a itemprop=\"url\" class=\"mkdf-cc-link mkdf-block-drag-link\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-10.png\" alt=\"audi\" \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-hover-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-10.png\" alt=\"audi\" \/>\n\t\t\t\t\t<\/a>\n\t<\/div><div class=\"mkdf-cc-item mkdf-item-space mkdf-cci-has-link\">\n\t\t\t<a itemprop=\"url\" class=\"mkdf-cc-link mkdf-block-drag-link\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-9.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-hover-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-9.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t<\/a>\n\t<\/div><div class=\"mkdf-cc-item mkdf-item-space mkdf-cci-has-link\">\n\t\t\t<a itemprop=\"url\" class=\"mkdf-cc-link mkdf-block-drag-link\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-hover-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-8.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t<\/a>\n\t<\/div><div class=\"mkdf-cc-item mkdf-item-space mkdf-cci-has-link\">\n\t\t\t<a itemprop=\"url\" class=\"mkdf-cc-link mkdf-block-drag-link\" href=\"#\" target=\"_self\">\n\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-2-1.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t\t\t<img decoding=\"async\" itemprop=\"image\" class=\"mkdf-cc-hover-image\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Diseno-sin-titulo-2-1.png\" alt=\"CONSTRUCTORA INDUSTRIAL\" \/>\n\t\t\t\t\t<\/a>\n\t<\/div>            <\/div>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-elementor-row\" style=\"\">\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dde7a84 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"3dde7a84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63561bcd\" data-id=\"63561bcd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dcc2a70 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3dcc2a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1>te podemos ayudar en:<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-text-holder mkdf-row-background-text-front\"><div class=\"mkdf-row-background-text-wrapper mkdf-row-background-text-animation mkdf-row-background-text-align-left\"><div class=\"mkdf-row-background-text-wrapper-inner\" style=\"font-size:180px;text-align:left;vertical-align:middle;padding-left:220px\" data-font-size-1440=180px data-font-size-1280=180px data-padding-left-size-1440=4.3% data-padding-left-size-1280=4.3%><div class=\"mkdf-row-background-text-1\">servicios<\/div><\/div><\/div><\/div><\/div>\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41df062 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"41df062\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c4f9d64\" data-id=\"c4f9d64\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b48a62d elementor-widget elementor-widget-image\" data-id=\"b48a62d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1.jpg\" class=\"attachment-large size-large wp-image-5249\" alt=\"a\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1.jpg 800w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-300x300.jpg 300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-150x150.jpg 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-768x768.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-650x650.jpg 650w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-600x600.jpg 600w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2019\/02\/h1-img-03-1-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e889e8d\" data-id=\"e889e8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9739e8e elementor-widget elementor-widget-mkdf_icon_with_text\" data-id=\"9739e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-iwt clearfix  mkdf-iwt-icon-top-centered mkdf-iwt-boxed mkdf-iwt-icon-medium\" >\n\t<div class=\"mkdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"375\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png\" class=\"attachment-full size-full\" alt=\"Constructora\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png 666w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-150x84.png 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-600x338.png 600w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/>                \t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"mkdf-iwt-content\" style=\"padding-top: px\">\n                    <p class=\"mkdf-iwt-caption\" >Conoce m\u00e1s<\/p>\n        \t\t\t\t\t<h4 class=\"mkdf-iwt-title\" style=\"margin-top: -4px\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/masonry\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<span class=\"mkdf-iwt-title-text\">Infraestructura met\u00e1lica<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<p class=\"mkdf-iwt-text\" style=\"margin-top: 14px\">Ofrecemos soluciones especializadas en el desarrollo, montaje y adecuaci\u00f3n de infraestructura met\u00e1lica para proyectos industriales. Nuestro equipo trabaja con precisi\u00f3n t\u00e9cnica en la instalaci\u00f3n y ajuste de estructuras met\u00e1licas que forman parte de naves industriales, ampliaciones estructurales y sistemas de soporte para diferentes procesos productivos.<\/p>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-21edfe1\" data-id=\"21edfe1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58a1102 elementor-widget elementor-widget-image\" data-id=\"58a1102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/NAVE-INDUSTRIAL-ARRIBA-650x650.jpg\" class=\"attachment-wilmer_mikado_image_square size-wilmer_mikado_image_square wp-image-9751\" alt=\"CONSTRUCTORA INDUSTRIAL\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/NAVE-INDUSTRIAL-ARRIBA-650x650.jpg 650w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/NAVE-INDUSTRIAL-ARRIBA-300x300.jpg 300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/NAVE-INDUSTRIAL-ARRIBA-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4df0d08 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"4df0d08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d36439\" data-id=\"1d36439\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2094dc8 elementor-widget elementor-widget-mkdf_icon_with_text\" data-id=\"2094dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-iwt clearfix  mkdf-iwt-icon-top-centered mkdf-iwt-boxed mkdf-iwt-icon-medium\" >\n\t<div class=\"mkdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/three-columns\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"375\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png\" class=\"attachment-full size-full\" alt=\"Constructora\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png 666w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-150x84.png 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-600x338.png 600w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/>                \t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"mkdf-iwt-content\" style=\"padding-top: px\">\n                    <p class=\"mkdf-iwt-caption\" >Conoce m\u00e1s<\/p>\n        \t\t\t\t\t<h4 class=\"mkdf-iwt-title\" style=\"margin-top: -4px\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/three-columns\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<span class=\"mkdf-iwt-title-text\">Obra civil<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<p class=\"mkdf-iwt-text\" style=\"margin-top: 14px\">Ejecutamos trabajos de obra civil enfocados en proyectos industriales, desarrollando cimentaciones, adecuaciones y sistemas de instalaciones necesarios para el correcto funcionamiento de la infraestructura.<\/p>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fb74a6f\" data-id=\"fb74a6f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b339f9 elementor-widget elementor-widget-image\" data-id=\"9b339f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/estructura-nave-indutrial-768x1024.jpg\" class=\"attachment-large size-large wp-image-9789\" alt=\"estructura-nave industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/estructura-nave-indutrial-768x1024.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/estructura-nave-indutrial-113x150.jpg 113w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/estructura-nave-indutrial-600x800.jpg 600w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/estructura-nave-indutrial.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa9a00e\" data-id=\"aa9a00e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a92aa6 elementor-widget elementor-widget-mkdf_icon_with_text\" data-id=\"7a92aa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_icon_with_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-iwt clearfix  mkdf-iwt-icon-top-centered mkdf-iwt-boxed mkdf-iwt-icon-medium\" >\n\t<div class=\"mkdf-iwt-icon\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/standard-shader\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"375\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png\" class=\"attachment-full size-full\" alt=\"Constructora\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview.png 666w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-150x84.png 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/Green_Modern_Content_Calendar_Marketing_Presentation-removebg-preview-600x338.png 600w\" sizes=\"(max-width: 666px) 100vw, 666px\" \/>                \t\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t<div class=\"mkdf-iwt-content\" style=\"padding-top: px\">\n                    <p class=\"mkdf-iwt-caption\" >Conoce m\u00e1s<\/p>\n        \t\t\t\t\t<h4 class=\"mkdf-iwt-title\" style=\"margin-top: -4px\">\n\t\t\t\t\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/portfolio\/standard-shader\/\" target=\"_self\">\n\t\t\t\t\t\t\t\t<span class=\"mkdf-iwt-title-text\">Tuber\u00edas industriales<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t<p class=\"mkdf-iwt-text\" style=\"margin-top: 14px\">Instalamos y ajustamos sistemas de tuber\u00edas industriales para diferentes procesos dentro de instalaciones productivas. Nuestro equipo realiza trabajos de ensamblaje, ajuste y mantenimiento garantizando el correcto funcionamiento de los sistemas.<\/p>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99bcede elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"99bcede\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-96bc213 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"96bc213\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-be38566 mkdf-appearing-section mkdf-eh-item-project\" data-id=\"be38566\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-884efb4 elementor-widget elementor-widget-mkdf_section_title\" data-id=\"884efb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-section-title-holder  mkdf-st-standard   \" >\n\t<div class=\"mkdf-st-inner\">\n        \t\t\t\t\t<h2 class=\"mkdf-st-title\" style=\"color: #FFFFFF\">\n\t\t\t\tExperiencia en proyectos industriales.\t\t\t<\/h2>\n\t\t\t\t\t\t\t<p class=\"mkdf-st-text\" style=\"color: #FFFFFF\">\n\t\t\t\tHemos participado en proyectos dentro de instalaciones industriales, realizando trabajos estructurales, adecuaciones de planta y soluciones constructivas especializadas para entornos de alta exigencia.\n\n\nProyecto destacado: Audi \u2013 Nave industrial A63.\t\t\t<\/p>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a02f44 elementor-widget elementor-widget-mkdf_button\" data-id=\"1a02f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/nuestros-clientes\/\" target=\"_self\" style=\"color: #F86B24;background-color: #FFFFFF;border-color: #FFFFFF\" class=\"mkdf-btn mkdf-btn-medium mkdf-btn-solid mkdf-btn-custom-hover-color\" data-hover-color=\"#F86B24\" 0=\"color: #F86B24\" 1=\"background-color: #FFFFFF\" 2=\"border-color: #FFFFFF\">\n    <span class=\"mkdf-btn-text\">Conoce m\u00e1s<\/span>\n    <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53de77b mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"53de77b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06b8b77\" data-id=\"06b8b77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b17847 elementor-widget elementor-widget-mkdf_counter\" data-id=\"6b17847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-counter-holder mkdf-shadow-counter   mkdf-counter-transparent-skin\" >\n\t<div class=\"mkdf-counter-inner clearfix\">\n        <div class=\"mkdf-counter-number mkdf-shadow-counter clearfix\">\n                                                <span class=\"mkdf-counter-background\"  style=\"-webkit-text-stroke-color: #DEDFE0\">+25<\/span>\n                                <span class=\"mkdf-counter mkdf-shadow-counter mkdf-zero-counter\" style=\"font-size: 60px;color: #001659\">+25<\/span>\n                    <\/div>\n        <div class=\"mkdf-counter-content mkdf-shadow-counter\">\n                            <p class=\"mkdf-counter-text\" >a\u00f1os de<\/p>\n                                        <h3 class=\"mkdf-counter-title\" >\n                    EXPERIENCIA                <\/h3>\n                    <\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb2bd22\" data-id=\"eb2bd22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82d8922 elementor-widget elementor-widget-mkdf_counter\" data-id=\"82d8922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-counter-holder mkdf-shadow-counter   mkdf-counter-transparent-skin\" >\n\t<div class=\"mkdf-counter-inner clearfix\">\n        <div class=\"mkdf-counter-number mkdf-shadow-counter clearfix\">\n                                                <span class=\"mkdf-counter-background\"  style=\"-webkit-text-stroke-color: #DEDFE0\">+30<\/span>\n                                <span class=\"mkdf-counter mkdf-shadow-counter mkdf-zero-counter\" style=\"font-size: 60px;color: #001659\">+30<\/span>\n                    <\/div>\n        <div class=\"mkdf-counter-content mkdf-shadow-counter\">\n                                        <h3 class=\"mkdf-counter-title\" >\n                    ESPECIALIDADES                <\/h3>\n                    <\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0bc932 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"d0bc932\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-461fb7a\" data-id=\"461fb7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1809f91 elementor-widget elementor-widget-mkdf_testimonials\" data-id=\"1809f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-testimonials-holder clearfix mkdf-testimonials-vertical-scroll \" >\n    <div class=\"mkdf-testimonials\" data-number-of-items=\"1\" data-enable-loop=\"yes\" data-enable-autoplay=\"yes\" data-slider-speed=\"5000\" data-slider-speed-animation=\"600\" data-enable-navigation=\"no\" data-enable-pagination=\"yes\" >\n        <div class=\"mkdf-testimonials-quote-holder\">\n            <svg x=\"0px\" y=\"0px\" width=\"154px\" height=\"123px\" viewBox=\"130 335.5 154 123\" style=\"enable-background:new 130 335.5 154 123;\" xml:space=\"preserve\">\n                <g>\n                    <g>\n                        <path d=\"M278.031,336.505v26.709c-15.584,0.437-23.484,11.185-23.484,31.964v6.833v1h1H283V457.5h-57.434\n                            c-5.813-18.085-8.76-35.984-8.76-53.211c0-20.312,5.314-36.878,15.794-49.236C242.868,342.944,258.149,336.707,278.031,336.505\n                             M192.677,336.505v26.708c-15.885,0.428-23.936,11.177-23.936,31.964v6.833v1h1h27.903V457.5h-57.448\n                            c-6.103-17.809-9.197-35.708-9.197-53.211c0-20.307,5.389-36.871,16.016-49.231C157.436,342.946,172.794,336.707,192.677,336.505\n                             M279.031,335.5c-20.773,0-36.509,6.306-47.193,18.905c-10.69,12.606-16.032,29.234-16.032,49.883\n                            c0,17.617,3.006,35.69,9.032,54.211H284v-56.489h-28.453v-6.833c0-20.649,7.827-30.977,23.484-30.977V335.5L279.031,335.5z\n                             M193.677,335.5c-20.774,0-36.581,6.306-47.419,18.905C135.419,367.012,130,383.639,130,404.289\n                            c0,17.924,3.161,35.989,9.484,54.211h59.161v-56.489h-28.903v-6.833c0-20.649,7.974-30.977,23.936-30.977V335.5L193.677,335.5z\"\/>\n                    <\/g>\n                <\/g>\n            <\/svg>\n        <\/div>\n        <div class=\"swiper-container\">\n            <div class=\"swiper-wrapper\">\n                \n                        <div class=\"mkdf-testimonial-content swiper-slide\" id=\"mkdf-testimonials-3804\">\n                                                            <div class=\"mkdf-testimonial-image\">\n                                    <img loading=\"lazy\" decoding=\"async\" width=\"193\" height=\"193\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-300x300.jpg\" class=\"attachment-193x193 size-193x193 wp-post-image\" alt=\"nave industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-300x300.jpg 300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-650x650.jpg 650w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/nave-industrial-100x100.jpg 100w\" sizes=\"(max-width: 193px) 100vw, 193px\" \/>                                <\/div>\n                                                        <div class=\"mkdf-testimonial-text-holder\">\n                                                                    <p class=\"mkdf-testimonial-text\">Participaci\u00f3n en la ejecuci\u00f3n de diversos trabajos estructurales dentro de la Nave Industrial A63, enfocados en el fortalecimiento y adecuaci\u00f3n de infraestructura met\u00e1lica bajo estrictos est\u00e1ndares de calidad y seguridad.<\/p>\n                                                                                                    <h6 class=\"mkdf-testimonial-author\">\n                                                                                    <span class=\"mkdf-testimonials-author-job\">EXPERIENCIA<\/span>\n                                                                            <\/h6>\n                                    <h4 class=\"mkdf-testimonial-author\">\n                                        <span class=\"mkdf-testimonials-author-name\">Audi<\/span>\n                                    <\/h4>\n                                                            <\/div>\n                        <\/div>\n\n                                <\/div>\n        <\/div>\n        <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ef3e2da elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"1ef3e2da\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ec676db\" data-id=\"5ec676db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"mkdf-elementor-row\" style=\"\">\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fbba056 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"fbba056\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-863e326\" data-id=\"863e326\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41d886cd elementor-widget elementor-widget-text-editor\" data-id=\"41d886cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1>PROYECTOS:<\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-text-holder mkdf-row-background-text-front\"><div class=\"mkdf-row-background-text-wrapper mkdf-row-background-text-animation mkdf-row-background-text-align-left\"><div class=\"mkdf-row-background-text-wrapper-inner\" style=\"font-size:180px;text-align:left;vertical-align:middle;padding-left:220px\" data-font-size-1440=180px data-font-size-1280=180px data-padding-left-size-1440=4.3% data-padding-left-size-1280=4.3%><div class=\"mkdf-row-background-text-1\">PROYECTOS<\/div><\/div><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f282de elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"5f282de\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4036123\" data-id=\"4036123\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1a508f elementor-widget elementor-widget-mkdf_team\" data-id=\"c1a508f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-team-holder mkdf-team-info-on-image\">\n\t<div class=\"mkdf-team-inner\">\n\t\t\t\t\t<div class=\"mkdf-team-image\">\n                                    <div class=\"mkdf-team-social-holder\">\n                                    <span class=\"mkdf-team-icon mkdf-team-social-opener\">\n                                        <span class=\"mkdf-icon-shortcode mkdf-normal\">\n                                            <a href=\"#\">\n                                                <span class=\"social_share mkdf-icon-element\"><\/span>\n                                            <\/a>\n                                        <\/span>\n                                    <\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.linkedin.com\/in\/brentac-construcciones-2832a43b5\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_linkedin mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.facebook.com\/profile.php?id=61588143166167\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_facebook mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.instagram.com\/brentac_construcciones\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_instagram mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                            <\/div>\n                                <img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"900\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/CONSTRUCTORA-2.jpg\" class=\"attachment-full size-full\" alt=\"CONSTRUCTORA\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/CONSTRUCTORA-2.jpg 720w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/CONSTRUCTORA-2-120x150.jpg 120w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/CONSTRUCTORA-2-600x750.jpg 600w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t<div class=\"mkdf-team-social-wrapper\" style=\"background-color: #00235A\">\n\t\t\t\t\t<div class=\"mkdf-team-social-outer\">\n\t\t\t\t\t\t<div class=\"mkdf-team-social-inner\" style=\"color: #FFFFFF\">\n                                                            <h6 class=\"mkdf-team-position\" style=\"color: #FFFFFF\">Proyecto Industrial \u2013 Nave A63<\/h6>\n                            \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"mkdf-team-name\" style=\"color: #FFFFFF\">Audi<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-425ea52\" data-id=\"425ea52\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d85b2e2 elementor-widget elementor-widget-mkdf_team\" data-id=\"d85b2e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-team-holder mkdf-team-info-on-image\">\n\t<div class=\"mkdf-team-inner\">\n\t\t\t\t\t<div class=\"mkdf-team-image\">\n                                    <div class=\"mkdf-team-social-holder\">\n                                    <span class=\"mkdf-team-icon mkdf-team-social-opener\">\n                                        <span class=\"mkdf-icon-shortcode mkdf-normal\">\n                                            <a href=\"#\">\n                                                <span class=\"social_share mkdf-icon-element\"><\/span>\n                                            <\/a>\n                                        <\/span>\n                                    <\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.linkedin.com\/in\/brentac-construcciones-2832a43b5\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_linkedin mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.facebook.com\/profile.php?id=61588143166167\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_facebook mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.instagram.com\/brentac_construcciones\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_instagram mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                            <\/div>\n                                <img loading=\"lazy\" decoding=\"async\" width=\"833\" height=\"1042\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion.jpg\" class=\"attachment-full size-full\" alt=\"plataforma de elevaci\u00f3n\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion.jpg 833w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion-819x1024.jpg 819w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion-120x150.jpg 120w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion-768x961.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/plataforma-de-elevacion-600x751.jpg 600w\" sizes=\"(max-width: 833px) 100vw, 833px\" \/>\t\t\t\t<div class=\"mkdf-team-social-wrapper\" style=\"background-color: #00235A\">\n\t\t\t\t\t<div class=\"mkdf-team-social-outer\">\n\t\t\t\t\t\t<div class=\"mkdf-team-social-inner\" style=\"color: #FFFFFF\">\n                                                            <h6 class=\"mkdf-team-position\" style=\"color: #FFFFFF\">Proyecto Industrial \u2013 Nave A63<\/h6>\n                            \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"mkdf-team-name\" style=\"color: #FFFFFF\">Audi<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-236c9cc\" data-id=\"236c9cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-efa644a elementor-widget elementor-widget-mkdf_team\" data-id=\"efa644a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-team-holder mkdf-team-info-on-image\">\n\t<div class=\"mkdf-team-inner\">\n\t\t\t\t\t<div class=\"mkdf-team-image\">\n                                    <div class=\"mkdf-team-social-holder\">\n                                    <span class=\"mkdf-team-icon mkdf-team-social-opener\">\n                                        <span class=\"mkdf-icon-shortcode mkdf-normal\">\n                                            <a href=\"#\">\n                                                <span class=\"social_share mkdf-icon-element\"><\/span>\n                                            <\/a>\n                                        <\/span>\n                                    <\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.linkedin.com\/in\/brentac-construcciones-2832a43b5\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_linkedin mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.facebook.com\/profile.php?id=61588143166167\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_facebook mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.instagram.com\/brentac_construcciones\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_instagram mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                            <\/div>\n                                <img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1.jpg\" class=\"attachment-full size-full\" alt=\"IMG-ESTRUCTURA INDUSTRIAL\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1.jpg 960w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1-819x1024.jpg 819w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1-120x150.jpg 120w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1-768x960.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/IMG-ESTRUCTURA-INDUSTRIAL-1-600x750.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t<div class=\"mkdf-team-social-wrapper\" style=\"background-color: #00235A\">\n\t\t\t\t\t<div class=\"mkdf-team-social-outer\">\n\t\t\t\t\t\t<div class=\"mkdf-team-social-inner\" style=\"color: #FFFFFF\">\n                                                            <h6 class=\"mkdf-team-position\" style=\"color: #FFFFFF\">Proyecto Industrial \u2013 Nave A63<\/h6>\n                            \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"mkdf-team-name\" style=\"color: #FFFFFF\">Audi<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-01590f8\" data-id=\"01590f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac935d0 elementor-widget elementor-widget-mkdf_team\" data-id=\"ac935d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-team-holder mkdf-team-info-on-image\">\n\t<div class=\"mkdf-team-inner\">\n\t\t\t\t\t<div class=\"mkdf-team-image\">\n                                    <div class=\"mkdf-team-social-holder\">\n                                    <span class=\"mkdf-team-icon mkdf-team-social-opener\">\n                                        <span class=\"mkdf-icon-shortcode mkdf-normal\">\n                                            <a href=\"#\">\n                                                <span class=\"social_share mkdf-icon-element\"><\/span>\n                                            <\/a>\n                                        <\/span>\n                                    <\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.linkedin.com\/in\/brentac-construcciones-2832a43b5\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_linkedin mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.facebook.com\/profile.php?id=61588143166167\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_facebook mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                                    <span class=\"mkdf-team-icon\" style=\"color: #FFFFFF\">    <span class=\"mkdf-icon-shortcode mkdf-normal   \">\n                    <a class=\"\" href=\"https:\/\/www.instagram.com\/brentac_construcciones\/\" target=\"_blank\">\n                    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant social_instagram mkdf-icon-element\"><\/span>                    <\/a>\n            <\/span>\n<\/span>\n                                            <\/div>\n                                <img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"636\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/soldadura-industrial.jpg\" class=\"attachment-full size-full\" alt=\"soldadura industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/soldadura-industrial.jpg 523w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2026\/03\/soldadura-industrial-123x150.jpg 123w\" sizes=\"(max-width: 523px) 100vw, 523px\" \/>\t\t\t\t<div class=\"mkdf-team-social-wrapper\" style=\"background-color: #00235A\">\n\t\t\t\t\t<div class=\"mkdf-team-social-outer\">\n\t\t\t\t\t\t<div class=\"mkdf-team-social-inner\" style=\"color: #FFFFFF\">\n                                                            <h6 class=\"mkdf-team-position\" style=\"color: #FFFFFF\">Proyecto Industrial \u2013 Nave A63<\/h6>\n                            \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"mkdf-team-name\" style=\"color: #FFFFFF\">Audi<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-952e3d3 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"952e3d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1d21d41\" data-id=\"1d21d41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb51ce8 elementor-widget elementor-widget-mkdf_pie_chart\" data-id=\"cb51ce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_pie_chart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-pie-chart-holder  text-below\">\n\t<div class=\"mkdf-pc-percentage\" data-percent=\"100\" data-bar-color=\"#AD0000\" data-track-color=\"#E8E8E9\">\n\t\t<span class=\"mkdf-pc-percent\" >100<\/span>\n        <svg class=\"mkdf-pie-chart-svg\" x=\"0px\" y=\"0px\" width=\"190px\" height=\"190px\" viewBox=\"0 0 190 190\">\n            <g>\n                <path style=\"fill: #E8E8E9\" d=\"M95,1c51.832,0,94,42.168,94,94s-42.168,94-94,94S1,146.832,1,95S43.168,1,95,1 M95,0 C42.533,0,0,42.533,0,95s42.533,95,95,95s95-42.533,95-95S147.467,0,95,0L95,0z\"\/>\n            <\/g>\n        <\/svg>\n    <\/div>\n\t\t\t<div class=\"mkdf-pc-text-holder\">\n            \t\t\t\t\t\t\t<h3 class=\"mkdf-pc-title\" >Confianza <\/h3>\n\t\t\t\t\t\t\t\t\t\t<p class=\"mkdf-pc-text\" >Construimos desde la confianza.<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-847957e\" data-id=\"847957e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-968b0b5 elementor-widget elementor-widget-mkdf_pie_chart\" data-id=\"968b0b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_pie_chart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-pie-chart-holder  text-below\">\n\t<div class=\"mkdf-pc-percentage\" data-percent=\"100\" data-bar-color=\"#BC0707\" data-track-color=\"#E8E8E9\">\n\t\t<span class=\"mkdf-pc-percent\" >100<\/span>\n        <svg class=\"mkdf-pie-chart-svg\" x=\"0px\" y=\"0px\" width=\"190px\" height=\"190px\" viewBox=\"0 0 190 190\">\n            <g>\n                <path style=\"fill: #E8E8E9\" d=\"M95,1c51.832,0,94,42.168,94,94s-42.168,94-94,94S1,146.832,1,95S43.168,1,95,1 M95,0 C42.533,0,0,42.533,0,95s42.533,95,95,95s95-42.533,95-95S147.467,0,95,0L95,0z\"\/>\n            <\/g>\n        <\/svg>\n    <\/div>\n\t\t\t<div class=\"mkdf-pc-text-holder\">\n            \t\t\t\t\t\t\t<h3 class=\"mkdf-pc-title\" >Seguridad<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p class=\"mkdf-pc-text\" >La integridad de nuestro equipo y de cada obra es de nuestros principales valores.\n<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3521b46\" data-id=\"3521b46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34afe52 elementor-widget elementor-widget-mkdf_pie_chart\" data-id=\"34afe52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_pie_chart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"mkdf-pie-chart-holder  text-below\">\n\t<div class=\"mkdf-pc-percentage\" data-percent=\"100\" data-bar-color=\"#9C0404\" data-track-color=\"#E8E8E9\">\n\t\t<span class=\"mkdf-pc-percent\" >100<\/span>\n        <svg class=\"mkdf-pie-chart-svg\" x=\"0px\" y=\"0px\" width=\"190px\" height=\"190px\" viewBox=\"0 0 190 190\">\n            <g>\n                <path style=\"fill: #E8E8E9\" d=\"M95,1c51.832,0,94,42.168,94,94s-42.168,94-94,94S1,146.832,1,95S43.168,1,95,1 M95,0 C42.533,0,0,42.533,0,95s42.533,95,95,95s95-42.533,95-95S147.467,0,95,0L95,0z\"\/>\n            <\/g>\n        <\/svg>\n    <\/div>\n\t\t\t<div class=\"mkdf-pc-text-holder\">\n            \t\t\t\t\t\t\t<h3 class=\"mkdf-pc-title\" >Calidad<\/h3>\n\t\t\t\t\t\t\t\t\t\t<p class=\"mkdf-pc-text\" >Supervisamos cada fase del proyecto.<\/p>\n\t\t\t\t\t<\/div>\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-elementor-row mkdf-row-with-bg-pattern\" style=\"\">\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a70ace mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"1a70ace\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-525eaae mkdf-appearing-section\" data-id=\"525eaae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dba6d8 elementor-widget elementor-widget-image\" data-id=\"8dba6d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-1024x1024.jpg\" class=\"attachment-large size-large wp-image-1229\" alt=\"Soldadura industrial\" srcset=\"https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-1024x1024.jpg 1024w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-300x300.jpg 300w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-150x150.jpg 150w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-768x768.jpg 768w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-650x650.jpg 650w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-600x600.jpg 600w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07-100x100.jpg 100w, https:\/\/brentac.com.mx\/wp-content\/uploads\/2018\/12\/h8-img-07.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-191bd0a\" data-id=\"191bd0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bfed3c3 elementor-widget elementor-widget-mkdf_accordion\" data-id=\"bfed3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"mkdf-accordion-holder mkdf-ac-default  mkdf-accordion mkdf-ac-boxed mkdf-white-skin mkdf-ac-with-bg-pattern  clearfix\">\n            <h4 class=\"mkdf-accordion-title\" >\n<span class=\"mkdf-tab-title\">Experiencia operativa<\/span>\n<span class=\"mkdf-accordion-mark\">\n\t\t<span class=\"mkdf_icon_plus icon_plus\"><\/span>\n\t\t<span class=\"mkdf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"mkdf-accordion-content\">\n    <div class=\"mkdf-accordion-content-inner\">\n        <p>Participamos en proyectos desarrollados dentro de instalaciones industriales, realizando trabajos especializados en infraestructura met\u00e1lica, obra civil, soldadura estructural y adecuaciones industriales..<\/p>    <\/div>\n<\/div><h4 class=\"mkdf-accordion-title\" >\n<span class=\"mkdf-tab-title\">Equipo humano especializado<\/span>\n<span class=\"mkdf-accordion-mark\">\n\t\t<span class=\"mkdf_icon_plus icon_plus\"><\/span>\n\t\t<span class=\"mkdf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"mkdf-accordion-content\">\n    <div class=\"mkdf-accordion-content-inner\">\n        <p>El personal que integra cada proyecto cuenta con experiencia en trabajos industriales que requieren conocimiento t\u00e9cnico, responsabilidad operativa y cumplimiento de procedimientos de seguridad.<\/p>    <\/div>\n<\/div><h4 class=\"mkdf-accordion-title\" >\n<span class=\"mkdf-tab-title\">Procesos de trabajo<\/span>\n<span class=\"mkdf-accordion-mark\">\n\t\t<span class=\"mkdf_icon_plus icon_plus\"><\/span>\n\t\t<span class=\"mkdf_icon_minus icon_minus-06\"><\/span>\n\t<\/span>\n<\/h4>\n<div class=\"mkdf-accordion-content\">\n    <div class=\"mkdf-accordion-content-inner\">\n        <p>Cada proyecto se desarrolla mediante procesos estructurados que permiten garantizar orden, eficiencia y control en todas las etapas de ejecuci\u00f3n.<\/p>    <\/div>\n<\/div>        <\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-pattern-holder\"><div class=\"mkdf-row-background-pattern-left\"><\/div><div class=\"mkdf-row-background-pattern-right\"><\/div><\/div><\/div>\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-356c8747 elementor-section-full_width elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-elementor-row-grid-no mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"356c8747\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-542fecaf\" data-id=\"542fecaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"mkdf-elementor-row\" style=\"\">\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-97155ae mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"97155ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-da224c0\" data-id=\"da224c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10d6318d elementor-widget elementor-widget-text-editor\" data-id=\"10d6318d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Cont\u00e1ctanos hoy y resolvemos todas tus dudas.<\/span><\/h2><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"mkdf-row-background-text-holder mkdf-row-background-text-front\"><div class=\"mkdf-row-background-text-wrapper mkdf-row-background-text-animation mkdf-row-background-text-align-left\"><div class=\"mkdf-row-background-text-wrapper-inner\" style=\"font-size:180px;color:#1E3C6F;-webkit-text-stroke-color:#1E3C6F;text-align:left;vertical-align:middle;padding-left:220px\" data-font-size-1440=180px data-font-size-1280=180px data-padding-left-size-1440=4.3% data-padding-left-size-1280=4.3%><div class=\"mkdf-row-background-text-1\">construye<\/div><\/div><\/div><\/div><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9dc3406 mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"9dc3406\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ec0c14\" data-id=\"2ec0c14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abab12b elementor-widget__width-auto elementor-widget elementor-widget-mkdf_button\" data-id=\"abab12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"mkdf_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a itemprop=\"url\" href=\"https:\/\/brentac.com.mx\/index.php\/contact-us\/\" target=\"_self\" style=\"color: #FFFFFF;padding: \" class=\"mkdf-btn mkdf-btn-medium mkdf-btn-simple mkdf-btn-custom-hover-color mkdf-btn-icon\" data-hover-color=\"#FFFFFF\" 0=\"color: #FFFFFF\" 1=\"padding: \">\n    <span class=\"mkdf-btn-text\">construye con nosotros<\/span>\n    <span aria-hidden=\"true\" class=\"mkdf-icon-font-elegant arrow_carrot-right \" ><\/span><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9710ec2 e-flex e-con-boxed e-con e-parent\" data-id=\"9710ec2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87b10cd mkdf-elementor-row-grid-section elementor-section-boxed elementor-section-height-default elementor-section-height-default mkdf-parallax-row-no mkdf-content-aligment-left mkdf-disabled-bg-image-bellow-no mkdf-row-btt-light\" data-id=\"87b10cd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca84f2a\" data-id=\"ca84f2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Desarrollo Integral de Proyectos de Obra Civil e Infraestructura Industrial \u00a0 Desde la cimentaci\u00f3n hasta la puesta en operaci\u00f3n, ejecutamos proyectos con enfoque en seguridad, trazabilidad, cumplimiento t\u00e9cnico y eficiencia operativa, alineados a est\u00e1ndares internacionales y requerimientos de plantas industriales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":129,"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":9846,"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions\/9846"}],"wp:attachment":[{"href":"https:\/\/brentac.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}